{"id":3,"name":"produccion","url":"","description":"","link":"https:\/\/evyan.es\/it\/author\/produccion\/","slug":"produccion","avatar_urls":{"24":"https:\/\/evyan.es\/wp-content\/litespeed\/avatar\/41fafc8d4939c7dcb2a260a8e3265b6d.jpg?ver=1784063604","48":"https:\/\/evyan.es\/wp-content\/litespeed\/avatar\/d2673bfaf57692d3aa6e1b2b1fba1b35.jpg?ver=1784063604","96":"https:\/\/evyan.es\/wp-content\/litespeed\/avatar\/f2841c1add833c5b5dc2e6bf8122059e.jpg?ver=1784063604"},"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>produccion, autor en Evyan<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/evyan.es\/it\/author\/produccion\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"profile\" \/>\n<meta property=\"og:title\" content=\"produccion, autor en Evyan\" \/>\n<meta property=\"og:url\" content=\"https:\/\/evyan.es\/author\/produccion\/\" \/>\n<meta property=\"og:site_name\" content=\"Evyan\" \/>\n<meta property=\"og:image\" content=\"https:\/\/secure.gravatar.com\/avatar\/0ac069a8af7a8c695861401d25768bdcce2c25903da39cadd9b8468527a7da64?s=500&d=mm&r=g\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"produccion, autor en Evyan","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/evyan.es\/it\/author\/produccion\/","og_locale":"it_IT","og_type":"profile","og_title":"produccion, autor en Evyan","og_url":"https:\/\/evyan.es\/author\/produccion\/","og_site_name":"Evyan","og_image":[{"url":"https:\/\/secure.gravatar.com\/avatar\/0ac069a8af7a8c695861401d25768bdcce2c25903da39cadd9b8468527a7da64?s=500&d=mm&r=g","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"ProfilePage","@id":"https:\/\/evyan.es\/author\/produccion\/","url":"https:\/\/evyan.es\/author\/produccion\/","name":"produccion, autor en Evyan","isPartOf":{"@id":"https:\/\/evyan.es\/it\/#website"},"breadcrumb":{"@id":"https:\/\/evyan.es\/author\/produccion\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/evyan.es\/author\/produccion\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/evyan.es\/author\/produccion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/evyan.es\/it\/"},{"@type":"ListItem","position":2,"name":"Archivo de produccion"}]},{"@type":"WebSite","@id":"https:\/\/evyan.es\/it\/#website","url":"https:\/\/evyan.es\/it\/","name":"Evyan","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/evyan.es\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/evyan.es\/it\/#\/schema\/person\/371642c6859f626fdf07adea1f9c0d1f","name":"produccion","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/evyan.es\/wp-content\/litespeed\/avatar\/f2841c1add833c5b5dc2e6bf8122059e.jpg?ver=1784063604","url":"https:\/\/evyan.es\/wp-content\/litespeed\/avatar\/f2841c1add833c5b5dc2e6bf8122059e.jpg?ver=1784063604","contentUrl":"https:\/\/evyan.es\/wp-content\/litespeed\/avatar\/f2841c1add833c5b5dc2e6bf8122059e.jpg?ver=1784063604","caption":"produccion"},"mainEntityOfPage":{"@id":"https:\/\/evyan.es\/author\/produccion\/"}}]}},"_links":{"self":[{"href":"https:\/\/evyan.es\/it\/wp-json\/wp\/v2\/users\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/evyan.es\/it\/wp-json\/wp\/v2\/users"}]}}